{"id":2715,"date":"2022-11-30T11:10:14","date_gmt":"2022-11-30T10:10:14","guid":{"rendered":"https:\/\/www.realschule-altenwalde.de\/wordpress\/?p=2715"},"modified":"2022-11-30T11:10:14","modified_gmt":"2022-11-30T10:10:14","slug":"schreibprojekt-anlaesslich-des-80-todestages-der-geschwister-scholl","status":"publish","type":"post","link":"https:\/\/www.realschule-altenwalde.de\/wordpress\/2022\/11\/30\/schreibprojekt-anlaesslich-des-80-todestages-der-geschwister-scholl\/","title":{"rendered":"Schreibprojekt anl\u00e4sslich des 80. Todestages der Geschwister Scholl"},"content":{"rendered":"<p>Hallo liebe Schollis, wir wollen euch heute \u00fcber das Schreibprojekt im Jahrgang neun aufmerksam machen. Es geht um die Geschwister-Scholl , deren Todestag sich am 22.02.2023 zum 80. Mal j\u00e4hrt.<\/p>\n<p><a href=\"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-scaled.jpeg\"><img loading=\"lazy\" class=\"size-medium wp-image-2716 alignleft\" src=\"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-300x225.jpeg 300w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-1024x768.jpeg 1024w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-768x576.jpeg 768w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-1536x1152.jpeg 1536w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-2048x1536.jpeg 2048w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-750x563.jpeg 750w, https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-content\/uploads\/2022\/11\/Projekt-80s-100x75.jpeg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Dieses Projekt wird von dem Verlagsleiter Herrn B\u00fcngen des Geestverlags\u00a0 geleitet und durch die Stiftung der EV.-luth. Kirchengemeinde, den Ortsrat und den F\u00f6rderverein finanziert. Der Jahrgang neun wird von den Lehrkr\u00e4ften Frau Andres, Frau Stache, Frau Sommer, Herrn Kausch und dem Verlagsleiter begleitet und organisiert. Die Jugendlichen werden im Haus der Jugend und dem Gemeindehaus Altenwalde vier Schreibvormittage verbringen, wo sie verschiedene Beitr\u00e4ge erstellen. Am Ende der vier Vormittage sollen aus den Beitr\u00e4gen, die die Sch\u00fcler gesammelt haben, ein eigenes Buch entstehen. Der erste Schreibtag fand am 28.11. statt und war gepr\u00e4gt von der Kreierung einer eigenen Identit\u00e4t in den 30er Jahren, Rollenspielen sowie dem Schreiben von Dialogen und Briefen.<\/p>\n<p>Dieses Buch wird an einer Lesung am 22.02.2023 von den Sch\u00fclern um 19 Uhr vorgetragen. Das Buch kann nach der Vorlesung durch Spendengelder erworben werden. Die Spendengelder erm\u00f6glichen den Druck mehrerer Exemplare. Man wird das Buch auch nach dem Tag, der Vorlesung kaufen k\u00f6nnen.<\/p>\n<p>Eure Scholli-News<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo liebe Schollis, wir wollen euch heute \u00fcber das Schreibprojekt im Jahrgang neun aufmerksam machen. Es geht um die Geschwister-Scholl , deren Todestag sich am 22.02.2023 zum 80. Mal j\u00e4hrt. Dieses Projekt wird von dem Verlagsleiter Herrn B\u00fcngen des Geestverlags\u00a0 geleitet und durch die Stiftung der EV.-luth. Kirchengemeinde, den Ortsrat und den F\u00f6rderverein finanziert. Der &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.realschule-altenwalde.de\/wordpress\/2022\/11\/30\/schreibprojekt-anlaesslich-des-80-todestages-der-geschwister-scholl\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[14,22],"tags":[],"_links":{"self":[{"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/posts\/2715"}],"collection":[{"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2715"}],"version-history":[{"count":1,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/posts\/2715\/revisions"}],"predecessor-version":[{"id":2717,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/posts\/2715\/revisions\/2717"}],"wp:attachment":[{"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.realschule-altenwalde.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}